{"id":256,"count":2,"description":"","link":"https:\/\/yourcanadianhome.com\/index.php\/category\/bestcasinogame13073\/","name":"bestcasinogame13073","slug":"bestcasinogame13073","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/yourcanadianhome.com\/index.php\/wp-json\/wp\/v2\/categories\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourcanadianhome.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/yourcanadianhome.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/yourcanadianhome.com\/index.php\/wp-json\/wp\/v2\/posts?categories=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}